{"id":8685,"date":"2017-07-19T06:58:11","date_gmt":"2017-07-19T06:58:11","guid":{"rendered":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente.jpg"},"modified":"2017-07-19T06:58:11","modified_gmt":"2017-07-19T06:58:11","slug":"dr-czompa-levente-2","status":"inherit","type":"attachment","link":"https:\/\/www.smiledesigncenter.hu\/sk\/dr-czompa-levente-2\/","title":{"rendered":"dr-czompa-levente"},"author":2,"comment_status":"open","ping_status":"closed","template":"","meta":[],"acf":[],"description":{"rendered":"\n<!-- Facebook Like Button Vivacity Infotech BEGIN -->\n<div class=\"fb-like\" data-href=\"https:\/\/www.smiledesigncenter.hu\/sk\/dr-czompa-levente-2\/\" data-layout=\"standard\" data-action=\"recommend\" data-show-faces=\"false\" data-size=\"small\" data-width=\"450\" data-share=\"1\" ><\/div>\n<!-- Facebook Like Button Vivacity Infotech END -->\n<p class=\"attachment\"><a href='https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente.jpg'><img loading=\"lazy\" width=\"300\" height=\"217\" src=\"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-300x217.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" srcset=\"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-300x217.jpg 300w, https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente.jpg 600w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":600,"height":433,"file":"2017\/07\/dr-czompa-levente.jpg","sizes":{"thumbnail":{"file":"dr-czompa-levente-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-150x150.jpg"},"medium":{"file":"dr-czompa-levente-300x217.jpg","width":300,"height":217,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-300x217.jpg"},"dental-care-team-single-thumb":{"file":"dr-czompa-levente-400x433.jpg","width":400,"height":433,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-400x433.jpg"},"dental-care-block-thumb":{"file":"dr-czompa-levente-370x260.jpg","width":370,"height":260,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-370x260.jpg"},"dental-care-featured-thumb":{"file":"dr-czompa-levente-600x400.jpg","width":600,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-600x400.jpg"},"dental-care-carousel-thumb":{"file":"dr-czompa-levente-450x400.jpg","width":450,"height":400,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-450x400.jpg"},"dental-care-brand-thumb":{"file":"dr-czompa-levente-220x120.jpg","width":220,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-220x120.jpg"},"dental-care-gallery-thumb":{"file":"dr-czompa-levente-500x433.jpg","width":500,"height":433,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-500x433.jpg"},"dental-care-product-carousel-thumb":{"file":"dr-czompa-levente-390x433.jpg","width":390,"height":433,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-390x433.jpg"},"dental-care-related-thumb":{"file":"dr-czompa-levente-400x250.jpg","width":400,"height":250,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-400x250.jpg"},"dental-care-blog-grid-widget-thumb":{"file":"dr-czompa-levente-480x420.jpg","width":480,"height":420,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente-480x420.jpg"},"full":{"file":"dr-czompa-levente.jpg","width":600,"height":433,"mime_type":"image\/jpeg","source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente.jpg"}},"image_meta":{"aperture":"0","credit":"","camera":"","caption":"","created_timestamp":"0","copyright":"","focal_length":"0","iso":"0","shutter_speed":"0","title":"","orientation":"0","keywords":[]}},"post":null,"source_url":"https:\/\/www.smiledesigncenter.hu\/wp-content\/uploads\/2017\/07\/dr-czompa-levente.jpg","_links":{"self":[{"href":"https:\/\/www.smiledesigncenter.hu\/sk\/wp-json\/wp\/v2\/media\/8685"}],"collection":[{"href":"https:\/\/www.smiledesigncenter.hu\/sk\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.smiledesigncenter.hu\/sk\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.smiledesigncenter.hu\/sk\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.smiledesigncenter.hu\/sk\/wp-json\/wp\/v2\/comments?post=8685"}]}}